{"id":8025,"date":"2025-03-14T16:45:00","date_gmt":"2025-03-14T19:45:00","guid":{"rendered":"https:\/\/tribunademinas.com.br\/colunas\/maistendencias\/?p=8025"},"modified":"2025-03-14T10:57:39","modified_gmt":"2025-03-14T13:57:39","slug":"cientistas-desvendam-misterio-sobre-pedras-movendo-sozinhas","status":"publish","type":"post","link":"https:\/\/tribunademinas.com.br\/colunas\/maistendencias\/cientistas-desvendam-misterio-sobre-pedras-movendo-sozinhas\/","title":{"rendered":"Cientistas desvendam mist\u00e9rio sobre pedras movendo sozinhas"},"content":{"rendered":"\n<p>Em 2013, cientistas da <a href=\"https:\/\/pmc.ncbi.nlm.nih.gov\/articles\/PMC4146553\/\" target=\"_blank\" rel=\"noopener\">Universidade da Calif\u00f3rnia em San Diego decidiram investigar<\/a> um fen\u00f4meno misterioso no Vale da Morte, na Calif\u00f3rnia. Para isso, equiparam 15 pedras com sensores de GPS, instalaram c\u00e2meras time-lapse e montaram uma esta\u00e7\u00e3o meteorol\u00f3gica para monitorar as condi\u00e7\u00f5es ambientais. Entre dezembro de 2013 e janeiro de 2014, conseguiram registrar o deslocamento de mais de 60 pedras, que se moviam a uma velocidade de dois a cinco metros por minuto.<\/p>\n\n\n\n<p>Esse fen\u00f4meno intrigava pesquisadores h\u00e1 mais de 50 anos. Rochas de at\u00e9 centenas de quilos, apelidadas de &#8220;rochas velejantes&#8221;, deixavam rastros de at\u00e9 460 metros na Racetrack Playa, uma \u00e1rea des\u00e9rtica plana cercada por montanhas. Apesar das marcas deixadas no solo, ningu\u00e9m havia presenciado o movimento das pedras at\u00e9 o estudo de 2013.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Pedras velejantes<\/strong><\/h2>\n\n\n\n<p>Os pesquisadores descobriram que o deslocamento das rochas depende de uma combina\u00e7\u00e3o incomum de condi\u00e7\u00f5es naturais. Durante as noites frias do deserto, uma fina camada de gelo se forma sobre o solo \u00famido da playa. Com o nascer do sol, esse gelo come\u00e7a a derreter, criando uma superf\u00edcie deslizante.<\/p>\n\n\n\n<p>Quando ventos fortes sopram na regi\u00e3o, as pedras s\u00e3o suavemente empurradas pelo terreno antes que a \u00e1gua se evapore por completo. O deslocamento das rochas \u00e9 um evento raro e pode levar anos para acontecer. Antes da pesquisa, a \u00faltima movimenta\u00e7\u00e3o registrada ocorreu em 2006.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Condi\u00e7\u00f5es e visita\u00e7\u00e3o<\/strong><\/h3>\n\n\n\n<p>H\u00e1 ind\u00edcios de que esse fen\u00f4meno tenha se tornado menos frequente desde os anos 1970, possivelmente devido \u00e0s mudan\u00e7as clim\u00e1ticas. De acordo com o pesquisador Ralph Lorenz, as noites frias, fundamentais para a forma\u00e7\u00e3o da camada de gelo que impulsiona as pedras, est\u00e3o se tornando menos comuns, o que pode amea\u00e7ar a continuidade desse processo natural.<\/p>\n\n\n\n<p>A Racetrack Playa \u00e9 resultado de mudan\u00e7as clim\u00e1ticas do passado. O local, que j\u00e1 foi um lago h\u00e1 cerca de 10 mil anos, secou com o fim da \u00faltima era glacial, abandonando uma superf\u00edcie de lama endurecida. Atualmente, a \u00e1rea \u00e9 aberta para visita\u00e7\u00e3o, mas o acesso \u00e9 remoto e exige cuidados, conforme orienta\u00e7\u00f5es do National Park Service.<\/p>\n\n\n\n<style>@media (min-width: 992px) {\n    .recomendadorV2Area1 {\n        width: 280px;\n    }\n    .recomendadorV2Area2 {\n        padding: 0px 20px;\n        width: calc(100% - 280px);\n    }\n}\n\n@media (max-width: 992px) {\n    .recomendadorV2Button {\n        margin: 0 auto;\n    }\n    .recomendadorV2Area {\n        flex-direction: column;\n        text-align: center;\n    }\n    .recomendadorV2Area2 {\n        padding: 0px 20px;\n    }\n}\n\n.recomendadorV2Area {\n    background: #eeeeee3d;\n    border-radius: 10px;\n    padding: 15px;\n    display: flex;\n    margin: 15px auto;\n    border: 1px solid #00000014;\n    max-width: 800px;\n}\n\n.recomendadorV2Area1 img {\n    width: 280px;\n    height: auto;\n    border-radius: 8px;\n}\n\n.linkrecomendadorv2 {\n    text-decoration: none !important;\n}\n\n.recomendadorV2Area2 .recomendadorV2Type {\n    text-transform: uppercase;\n    font-weight: 500;\n    font-size: 11px;\n    letter-spacing: 2px;\n    color: #666;\n    margin: 12px 0;\n    display: block;\n}\n\n.recomendadorV2Title h2 {\n    padding-top: 0px !important;\n    margin: 0px !important;\n    border-left: none !important;\n    padding-left: 0px !important;\n    line-height: 1.3;\n    color: #000 !important;\n    font-size: 24px;\n    margin-bottom: 12px !important;\n}\n\n.recomendadorV2Desc {\n    color: #333;\n    margin: 12px 0px !important;\n    font-size: 15px;\n    line-height: 1.5;\n}\n\n.recomendadorV2Button {\n    width: auto;\n    max-width: 200px;\n    margin: 0;\n    display: inline-flex;\n    align-items: center;\n    background: #1D3557;\n    border-radius: 8px;\n    color: #fff;\n    height: 36px;\n    justify-content: center;\n    text-align: center;\n    font-size: 14px;\n    padding: 0 20px;\n    transition: background-color 0.2s ease;\n}\n\n.recomendadorV2Button:hover {\n    background: #2a4d7a;\n}\n\n.recomendadorV2Button:after {\n    margin-top: -2px;\n    content: \"\u2192\";\n    padding: 0px 0px 0px 8px;\n}\n\n.recomendadorV2Alert {\n    text-align: left;\n    font-size: 11px;\n    margin-top: 8px;\n    color: #666;\n}\n\n.recomendadorFixedArea {\n    width: 100%;\n    display: flex;\n    justify-content: center;\n    align-items: center;\n}\n\n@media (min-width: 992px) {\n    #recomendadorFixed {\n        width: 32% !important;\n        left: 5%;\n    }\n    .recomendadorCloseFixed{\n        right: inherit !important;\n        left: 378px !important;\n    }\n}\n\n#recomendadorFixed {\n    width: 90%;\n    box-shadow: 0 10px 20px 0px #00000057;\n    display: none;\n    height: 90px;\n    background: #F6F6F6;\n    position: fixed;\n    flex-direction: row;\n    bottom: 10px;\n    z-index: 9999;\n    border-radius: 16px;\n    padding: 7px 10px;\n}\n\n.recomendadorLeftArea {\n    width: 160px;\n}\n\n.recomendadorRightArea h2 {\n    padding-top: 0px;\n    margin: 2px 0px 4px 0px !important;\n    font-weight: 400;\n    text-align: center;\n    padding-left: 0px !important;\n    color: #000 !important;\n    border-left: none !important;\n    line-height: 20px;\n    font-size: 12px !important;\n}\n\n.recomendadorImgFixed {\n    overflow: hidden;\n    padding: 8px 6px;\n    height: 100%;\n}\n\n.recomendadorImgFixed img {\n    height: 100% !important;\n    border-radius: 16px;\n}\n\n.recomendadorRightArea {\n    padding-top: 6px;\n    display: flex;\n    width: calc(100% - 130px);\n    justify-content: space-between;\n    align-items: center;\n    flex-direction: column;\n}\n\n.recomendadorButtonFixed {\n    margin: 0 auto;\n    background: #1D3557;\n    width: 80%;\n    text-align: center;\n    font-size: 10px;\n    color: #FFF;\n    padding: 2px 10px;\n    border-radius: 3px;\n}\n\n.recomendadorButtonFixed:after {\n    margin-top: -3px;\n    content: \"\u2192\";\n    padding: 0px 0px 0px 10px;\n}\n\n.recomendadorAlertFixed {\n    font-weight: 400;\n    text-align: center;\n    color: #484848;\n    font-size: 8px;\n}\n\n.recomendadorCloseFixed {\n    z-index: 99999;\n    display: none;\n    right: 0px;\n    left: inherit;\n    bottom: 99px;\n    position: fixed;\n    justify-content: center;\n    background: #F6F6F6;\n    width: 25px;\n    align-items: center;\n    height: 25px;\n    font-weight: 800;\n    border-radius: 50%;\n    border: 1px solid #EBEBEB;\n}\n\n.recomendadorV2Desc{\n    color: #000000;\n    margin: 20px 0px;\n}\n\n@media (max-width: 576px) {\n    .recomendadorV2Area {\n      padding: 10px;\n      max-width: 100%;\n    }\n  \n    .recomendadorV2Area1 img {\n      width: 100%;\n      border-radius: 6px;\n    }\n  \n    .recomendadorV2Area2 .recomendadorV2Type {\n      font-size: 9px;\n      letter-spacing: 1px;\n      margin: 8px 0;\n    }\n  \n    .recomendadorV2Title h2 {\n      font-size: 18px !important;\n      margin-bottom: 8px !important;\n      line-height: 1.2;\n    }\n  \n    .recomendadorV2Desc {\n      font-size: 14px;\n      margin: 8px 0 !important;\n      line-height: 1.4;\n    }\n  \n    .recomendadorV2Button {\n      font-size: 14px;\n      height: 40px;\n      padding: 0 12px;\n      max-width: 100%;\n      width: 100%;\n    }\n  \n    .recomendadorV2Button:after {\n      padding-left: 6px;\n    }\n  }\n  <\/style>\n        <div class=\"lazyblock-recomendador-v2-2jDGz wp-block-lazyblock-recomendador-v2\">\n        <a class=\"linkrecomendadorv2\" href=\"https:\/\/tribunademinas.com.br\/colunas\/maistendencias\/tres-maiores-especies-de-dinossauros-viviam-no-maior-deserto-do-mundo\/\">\n            <div class=\"recomendadorV2Area\">\n            <div class=\"recomendadorV2Area1\">\n                <div class=\"recomendadorV2Img\">\n                <img class=\"lazyloaded\" decoding=\"async\" src=\"https:\/\/tribunademinas.com.br\/colunas\/maistendencias\/wp-content\/uploads\/2025\/01\/000000-54.jpg\" data-src=\"https:\/\/tribunademinas.com.br\/colunas\/maistendencias\/wp-content\/uploads\/2025\/01\/000000-54.jpg\" alt=\"\">\n                <\/div>\n            <\/div>\n            <div class=\"recomendadorV2Area2\">\n                <div class=\"recomendadorV2Type\">\n                    <span> Registros arqueol\u00f3gicos <\/span>\n                <\/div>\n                <div class=\"recomendadorV2Title\">\n                <h2><span> Tr\u00eas maiores esp\u00e9cies de dinossauros viviam no maior deserto do mundo<\/span><\/h2>\n                <\/div>\n                <div class=\"recomendadorV2Desc\">\n                <span> Onde hoje se localiza o maior deserto do planeta, a milhares de anos atr\u00e1s era a casa de perigosos dinossauros e rios abundantes<\/span>\n                <\/div>\n                <div class=\"recomendadorV2Button\"> Saiba os detalhes<\/div>\n                <div class=\"recomendadorV2Alert\"><\/div>\n            <\/div>\n            <\/div>\n        <\/a>\n        <div>\n            <div style=\"z-index:99999;\" id=\"buttonClose\" onclick=\"closeRecomendadorFixed()\">\n            <div class=\"recomendadorCloseFixed\">X<\/div>\n            <\/div>\n            <a href=\"https:\/\/tribunademinas.com.br\/colunas\/maistendencias\/tres-maiores-especies-de-dinossauros-viviam-no-maior-deserto-do-mundo\/\">\n            <div class=\"recomendadorFixedArea\">\n                <div id=\"recomendadorFixed\">\n                <div class=\"recomendadorLeftArea\">\n                    <div class=\"recomendadorImgFixed\">\n                    <img class=\"lazyload\" decoding=\"async\" src=\"https:\/\/tribunademinas.com.br\/colunas\/maistendencias\/wp-content\/uploads\/2025\/01\/000000-54.jpg\" alt=\"\">\n                    <\/div>\n                <\/div>\n                <div class=\"recomendadorRightArea\">\n                    <div class=\"recomendadorTitleFixed\">\n                    <h2><span> Tr\u00eas maiores esp\u00e9cies de dinossauros viviam no maior deserto do mundo<\/span><\/h2>\n                    <\/div>\n                    <div class=\"recomendadorButtonFixed\"> Saiba os detalhes<\/div>\n                    <div class=\"recomendadorAlertFixed\"><\/div>\n                <\/div>\n                <\/div>\n            <\/div>\n            <\/a>\n        <\/div>\n        <\/div>\n","protected":false},"excerpt":{"rendered":"<p>Durante mais de 50 anos, pedras deixaram rastros como se estivessem andando e ningu\u00e9m conseguia entender como; veja a solu\u00e7\u00e3o do mist\u00e9rio<\/p>\n","protected":false},"author":3,"featured_media":8026,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":{"format":"standard"},"jnews_primary_category":[],"jnews_social_meta":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":""},"categories":[84,83],"tags":[],"class_list":["post-8025","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mais-tendencias","category-colunas"],"_referencia":"","_links":{"self":[{"href":"https:\/\/tribunademinas.com.br\/colunas\/maistendencias\/wp-json\/wp\/v2\/posts\/8025","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tribunademinas.com.br\/colunas\/maistendencias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tribunademinas.com.br\/colunas\/maistendencias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tribunademinas.com.br\/colunas\/maistendencias\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/tribunademinas.com.br\/colunas\/maistendencias\/wp-json\/wp\/v2\/comments?post=8025"}],"version-history":[{"count":1,"href":"https:\/\/tribunademinas.com.br\/colunas\/maistendencias\/wp-json\/wp\/v2\/posts\/8025\/revisions"}],"predecessor-version":[{"id":8027,"href":"https:\/\/tribunademinas.com.br\/colunas\/maistendencias\/wp-json\/wp\/v2\/posts\/8025\/revisions\/8027"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tribunademinas.com.br\/colunas\/maistendencias\/wp-json\/wp\/v2\/media\/8026"}],"wp:attachment":[{"href":"https:\/\/tribunademinas.com.br\/colunas\/maistendencias\/wp-json\/wp\/v2\/media?parent=8025"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tribunademinas.com.br\/colunas\/maistendencias\/wp-json\/wp\/v2\/categories?post=8025"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tribunademinas.com.br\/colunas\/maistendencias\/wp-json\/wp\/v2\/tags?post=8025"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}