{"id":7652,"date":"2025-03-12T19:45:00","date_gmt":"2025-03-12T22:45:00","guid":{"rendered":"https:\/\/tribunademinas.com.br\/colunas\/maistendencias\/?p=7652"},"modified":"2025-03-12T12:39:44","modified_gmt":"2025-03-12T15:39:44","slug":"oi-fibra-deixa-de-existir-e-novo-nome-e-divulgado","status":"publish","type":"post","link":"https:\/\/tribunademinas.com.br\/colunas\/maistendencias\/oi-fibra-deixa-de-existir-e-novo-nome-e-divulgado\/","title":{"rendered":"Oi Fibra deixa de existir e novo nome \u00e9 divulgado"},"content":{"rendered":"\n<p>Nos pr\u00f3ximos meses, a Oi Fibra adotar\u00e1 um novo nome e passar\u00e1 a se chamar <a href=\"https:\/\/www.niointernet.com.br\/\" target=\"_blank\" rel=\"noopener\">Nio<\/a>. A mudan\u00e7a ocorre ap\u00f3s sua venda para a V.tal, companhia sob gest\u00e3o de fundos do BTG Pactual. Com a conclus\u00e3o da transa\u00e7\u00e3o em fevereiro, no valor de R$ 5,75 bilh\u00f5es, a opera\u00e7\u00e3o de banda larga se desvinculou da antiga controladora, ganhando autonomia para seguir uma nova estrat\u00e9gia no mercado.<\/p>\n\n\n\n<p>O nome Nio foi selecionado para representar modernidade e inova\u00e7\u00e3o, mesmo sendo uma empresa j\u00e1 estabelecida no setor de telecomunica\u00e7\u00f5es. A transi\u00e7\u00e3o para a nova identidade ocorrer\u00e1 de forma gradual nos pr\u00f3ximos meses, enquanto a companhia define sua estrat\u00e9gia para se firmar como uma operadora digital diferenciada.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Clientes da Oi Fibra<\/strong><\/h2>\n\n\n\n<p>Com uma base de 4 milh\u00f5es de clientes e 8% de participa\u00e7\u00e3o no mercado de internet fixa, a Nio ocupa a terceira posi\u00e7\u00e3o entre as maiores provedoras do Brasil, atr\u00e1s da Vivo, que possui 7,4 milh\u00f5es de assinantes, e da Claro, com 10,2 milh\u00f5es. Sua infraestrutura de fibra \u00f3ptica j\u00e1 alcan\u00e7a 22 milh\u00f5es de endere\u00e7os, proporcionando um grande potencial de expans\u00e3o. No momento, a empresa registra uma receita l\u00edquida anual de R$ 4,5 bilh\u00f5es.<\/p>\n\n\n\n<p>Os clientes da Oi Fibra ser\u00e3o migrados automaticamente para a Nio, sem mudan\u00e7as nos planos j\u00e1 contratados. Sob a lideran\u00e7a de Marcio Fabbris, a nova administra\u00e7\u00e3o enfrentar\u00e1 o desafio de fortalecer a opera\u00e7\u00e3o ap\u00f3s um per\u00edodo de queda na base de assinantes, resultado das dificuldades financeiras enfrentadas pela Oi.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Planos da nova gest\u00e3o<\/strong><\/h3>\n\n\n\n<p>De acordo com Fabbris, a prioridade inicial ser\u00e1 consolidar a identidade da marca, reconquistar clientes e estimular o crescimento sustent\u00e1vel. Em comunicado, a empresa refor\u00e7ou seu compromisso em oferecer um servi\u00e7o mais acess\u00edvel, \u00e1gil e transparente para os consumidores.<\/p>\n\n\n\n<p>Para alcan\u00e7ar esse objetivo, pretende ampliar sua oferta de servi\u00e7os digitais, firmando parcerias com plataformas de streaming e desenvolvendo solu\u00e7\u00f5es voltadas tanto para a conectividade dom\u00e9stica quanto para o segmento corporativo. A equipe de gest\u00e3o combinar\u00e1 ex-executivos da Oi com profissionais de diferentes setores, agregando uma nova perspectiva ao neg\u00f3cio.<\/p>\n\n\n\n<style>@media (min-width: 992px) {\n    .recomendadorV2Area1 {\n        width: 280px;\n    }\n    .recomendadorV2Area2 {\n        padding: 0px 20px;\n        width: calc(100% - 280px);\n    }\n}\n\n@media (max-width: 992px) {\n    .recomendadorV2Button {\n        margin: 0 auto;\n    }\n    .recomendadorV2Area {\n        flex-direction: column;\n        text-align: center;\n    }\n    .recomendadorV2Area2 {\n        padding: 0px 20px;\n    }\n}\n\n.recomendadorV2Area {\n    background: #eeeeee3d;\n    border-radius: 10px;\n    padding: 15px;\n    display: flex;\n    margin: 15px auto;\n    border: 1px solid #00000014;\n    max-width: 800px;\n}\n\n.recomendadorV2Area1 img {\n    width: 280px;\n    height: auto;\n    border-radius: 8px;\n}\n\n.linkrecomendadorv2 {\n    text-decoration: none !important;\n}\n\n.recomendadorV2Area2 .recomendadorV2Type {\n    text-transform: uppercase;\n    font-weight: 500;\n    font-size: 11px;\n    letter-spacing: 2px;\n    color: #666;\n    margin: 12px 0;\n    display: block;\n}\n\n.recomendadorV2Title h2 {\n    padding-top: 0px !important;\n    margin: 0px !important;\n    border-left: none !important;\n    padding-left: 0px !important;\n    line-height: 1.3;\n    color: #000 !important;\n    font-size: 24px;\n    margin-bottom: 12px !important;\n}\n\n.recomendadorV2Desc {\n    color: #333;\n    margin: 12px 0px !important;\n    font-size: 15px;\n    line-height: 1.5;\n}\n\n.recomendadorV2Button {\n    width: auto;\n    max-width: 200px;\n    margin: 0;\n    display: inline-flex;\n    align-items: center;\n    background: #1D3557;\n    border-radius: 8px;\n    color: #fff;\n    height: 36px;\n    justify-content: center;\n    text-align: center;\n    font-size: 14px;\n    padding: 0 20px;\n    transition: background-color 0.2s ease;\n}\n\n.recomendadorV2Button:hover {\n    background: #2a4d7a;\n}\n\n.recomendadorV2Button:after {\n    margin-top: -2px;\n    content: \"\u2192\";\n    padding: 0px 0px 0px 8px;\n}\n\n.recomendadorV2Alert {\n    text-align: left;\n    font-size: 11px;\n    margin-top: 8px;\n    color: #666;\n}\n\n.recomendadorFixedArea {\n    width: 100%;\n    display: flex;\n    justify-content: center;\n    align-items: center;\n}\n\n@media (min-width: 992px) {\n    #recomendadorFixed {\n        width: 32% !important;\n        left: 5%;\n    }\n    .recomendadorCloseFixed{\n        right: inherit !important;\n        left: 378px !important;\n    }\n}\n\n#recomendadorFixed {\n    width: 90%;\n    box-shadow: 0 10px 20px 0px #00000057;\n    display: none;\n    height: 90px;\n    background: #F6F6F6;\n    position: fixed;\n    flex-direction: row;\n    bottom: 10px;\n    z-index: 9999;\n    border-radius: 16px;\n    padding: 7px 10px;\n}\n\n.recomendadorLeftArea {\n    width: 160px;\n}\n\n.recomendadorRightArea h2 {\n    padding-top: 0px;\n    margin: 2px 0px 4px 0px !important;\n    font-weight: 400;\n    text-align: center;\n    padding-left: 0px !important;\n    color: #000 !important;\n    border-left: none !important;\n    line-height: 20px;\n    font-size: 12px !important;\n}\n\n.recomendadorImgFixed {\n    overflow: hidden;\n    padding: 8px 6px;\n    height: 100%;\n}\n\n.recomendadorImgFixed img {\n    height: 100% !important;\n    border-radius: 16px;\n}\n\n.recomendadorRightArea {\n    padding-top: 6px;\n    display: flex;\n    width: calc(100% - 130px);\n    justify-content: space-between;\n    align-items: center;\n    flex-direction: column;\n}\n\n.recomendadorButtonFixed {\n    margin: 0 auto;\n    background: #1D3557;\n    width: 80%;\n    text-align: center;\n    font-size: 10px;\n    color: #FFF;\n    padding: 2px 10px;\n    border-radius: 3px;\n}\n\n.recomendadorButtonFixed:after {\n    margin-top: -3px;\n    content: \"\u2192\";\n    padding: 0px 0px 0px 10px;\n}\n\n.recomendadorAlertFixed {\n    font-weight: 400;\n    text-align: center;\n    color: #484848;\n    font-size: 8px;\n}\n\n.recomendadorCloseFixed {\n    z-index: 99999;\n    display: none;\n    right: 0px;\n    left: inherit;\n    bottom: 99px;\n    position: fixed;\n    justify-content: center;\n    background: #F6F6F6;\n    width: 25px;\n    align-items: center;\n    height: 25px;\n    font-weight: 800;\n    border-radius: 50%;\n    border: 1px solid #EBEBEB;\n}\n\n.recomendadorV2Desc{\n    color: #000000;\n    margin: 20px 0px;\n}\n\n@media (max-width: 576px) {\n    .recomendadorV2Area {\n      padding: 10px;\n      max-width: 100%;\n    }\n  \n    .recomendadorV2Area1 img {\n      width: 100%;\n      border-radius: 6px;\n    }\n  \n    .recomendadorV2Area2 .recomendadorV2Type {\n      font-size: 9px;\n      letter-spacing: 1px;\n      margin: 8px 0;\n    }\n  \n    .recomendadorV2Title h2 {\n      font-size: 18px !important;\n      margin-bottom: 8px !important;\n      line-height: 1.2;\n    }\n  \n    .recomendadorV2Desc {\n      font-size: 14px;\n      margin: 8px 0 !important;\n      line-height: 1.4;\n    }\n  \n    .recomendadorV2Button {\n      font-size: 14px;\n      height: 40px;\n      padding: 0 12px;\n      max-width: 100%;\n      width: 100%;\n    }\n  \n    .recomendadorV2Button:after {\n      padding-left: 6px;\n    }\n  }\n  <\/style>\n        <div class=\"lazyblock-recomendador-v2-2jDGz wp-block-lazyblock-recomendador-v2\">\n        <a class=\"linkrecomendadorv2\" href=\"https:\/\/tribunademinas.com.br\/colunas\/maistendencias\/descobrimos-o-que-vai-acontecer-apos-o-fim-do-chip-de-celulares\/\">\n            <div class=\"recomendadorV2Area\">\n            <div class=\"recomendadorV2Area1\">\n                <div class=\"recomendadorV2Img\">\n                <img class=\"lazyloaded\" decoding=\"async\" src=\"https:\/\/tribunademinas.com.br\/colunas\/maistendencias\/wp-content\/uploads\/2025\/02\/000000-51.jpg\" data-src=\"https:\/\/tribunademinas.com.br\/colunas\/maistendencias\/wp-content\/uploads\/2025\/02\/000000-51.jpg\" alt=\"\">\n                <\/div>\n            <\/div>\n            <div class=\"recomendadorV2Area2\">\n                <div class=\"recomendadorV2Type\">\n                    <span> Novidade<\/span>\n                <\/div>\n                <div class=\"recomendadorV2Title\">\n                <h2><span> Selecionar Descobrimos o que vai acontecer ap\u00f3s o fim do chip de celulares\t<\/span><\/h2>\n                <\/div>\n                <div class=\"recomendadorV2Desc\">\n                <span> As operadoras de celular j\u00e1 est\u00e3o ofertando um novo modelo de \u2018chip\u2019 para os celulares; entenda a novidade e como funciona a troca<\/span>\n                <\/div>\n                <div class=\"recomendadorV2Button\"> Veja agora<\/div>\n                <div class=\"recomendadorV2Alert\"><\/div>\n            <\/div>\n            <\/div>\n        <\/a>\n        <div>\n            <div style=\"z-index:99999;\" id=\"buttonClose\" onclick=\"closeRecomendadorFixed()\">\n            <div class=\"recomendadorCloseFixed\">X<\/div>\n            <\/div>\n            <a href=\"https:\/\/tribunademinas.com.br\/colunas\/maistendencias\/descobrimos-o-que-vai-acontecer-apos-o-fim-do-chip-de-celulares\/\">\n            <div class=\"recomendadorFixedArea\">\n                <div id=\"recomendadorFixed\">\n                <div class=\"recomendadorLeftArea\">\n                    <div class=\"recomendadorImgFixed\">\n                    <img class=\"lazyload\" decoding=\"async\" src=\"https:\/\/tribunademinas.com.br\/colunas\/maistendencias\/wp-content\/uploads\/2025\/02\/000000-51.jpg\" alt=\"\">\n                    <\/div>\n                <\/div>\n                <div class=\"recomendadorRightArea\">\n                    <div class=\"recomendadorTitleFixed\">\n                    <h2><span> Selecionar Descobrimos o que vai acontecer ap\u00f3s o fim do chip de celulares\t<\/span><\/h2>\n                    <\/div>\n                    <div class=\"recomendadorButtonFixed\"> Veja agora<\/div>\n                    <div class=\"recomendadorAlertFixed\"><\/div>\n                <\/div>\n                <\/div>\n            <\/div>\n            <\/a>\n        <\/div>\n        <\/div>\n","protected":false},"excerpt":{"rendered":"<p>A Oi Fibra foi vendida para uma empresa do BTG Pactual e ir\u00e1 mudar de nome; saiba os detalhes da transi\u00e7\u00e3o e como ficam os clientes<\/p>\n","protected":false},"author":3,"featured_media":7653,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":{"format":"standard"},"jnews_primary_category":[],"jnews_social_meta":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":""},"categories":[84,83],"tags":[],"class_list":["post-7652","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mais-tendencias","category-colunas"],"_referencia":"","_links":{"self":[{"href":"https:\/\/tribunademinas.com.br\/colunas\/maistendencias\/wp-json\/wp\/v2\/posts\/7652","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tribunademinas.com.br\/colunas\/maistendencias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tribunademinas.com.br\/colunas\/maistendencias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tribunademinas.com.br\/colunas\/maistendencias\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/tribunademinas.com.br\/colunas\/maistendencias\/wp-json\/wp\/v2\/comments?post=7652"}],"version-history":[{"count":1,"href":"https:\/\/tribunademinas.com.br\/colunas\/maistendencias\/wp-json\/wp\/v2\/posts\/7652\/revisions"}],"predecessor-version":[{"id":7658,"href":"https:\/\/tribunademinas.com.br\/colunas\/maistendencias\/wp-json\/wp\/v2\/posts\/7652\/revisions\/7658"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tribunademinas.com.br\/colunas\/maistendencias\/wp-json\/wp\/v2\/media\/7653"}],"wp:attachment":[{"href":"https:\/\/tribunademinas.com.br\/colunas\/maistendencias\/wp-json\/wp\/v2\/media?parent=7652"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tribunademinas.com.br\/colunas\/maistendencias\/wp-json\/wp\/v2\/categories?post=7652"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tribunademinas.com.br\/colunas\/maistendencias\/wp-json\/wp\/v2\/tags?post=7652"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}