{"id":3449,"date":"2025-01-30T15:20:00","date_gmt":"2025-01-30T18:20:00","guid":{"rendered":"https:\/\/tribunademinas.com.br\/colunas\/maistendencias\/?p=3449"},"modified":"2025-01-30T11:14:25","modified_gmt":"2025-01-30T14:14:25","slug":"o-que-muda-em-2025-sobre-imposto-para-quem-ganhar-heranca","status":"publish","type":"post","link":"https:\/\/tribunademinas.com.br\/colunas\/maistendencias\/o-que-muda-em-2025-sobre-imposto-para-quem-ganhar-heranca\/","title":{"rendered":"O que muda em 2025 sobre imposto para quem ganhar heran\u00e7a"},"content":{"rendered":"\n<p>Uma recente decis\u00e3o do Supremo Tribunal Federal (STF) est\u00e1 modificando a maneira de cobran\u00e7a do Imposto sobre Transmiss\u00e3o Causa Mortis e Doa\u00e7\u00e3o (ITCMD), conhecido como imposto sobre heran\u00e7a, em rela\u00e7\u00e3o aos planos de previd\u00eancia privada aberta, como o PGBL e o VGBL.<\/p>\n\n\n\n<p>No final do ano passado, o STF decidiu por unanimidade que os benefici\u00e1rios desses planos estar\u00e3o isentos do pagamento do ITCMD, imposto estadual que incide sobre a transfer\u00eancia de bens por heran\u00e7a ou doa\u00e7\u00e3o. Essa isen\u00e7\u00e3o ser\u00e1 aplic\u00e1vel em todos os estados do Brasil, independentemente das al\u00edquotas locais.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Mudan\u00e7a no imposto<\/strong><\/h2>\n\n\n\n<p>Al\u00e9m de trazer benef\u00edcios aos contribuintes, a decis\u00e3o destaca a import\u00e2ncia da previd\u00eancia privada no planejamento sucess\u00f3rio. Com essa mudan\u00e7a, os benefici\u00e1rios podem ser definidos sem a necessidade de invent\u00e1rio ou seguir as normas da sucess\u00e3o legal.<\/p>\n\n\n\n<p>De acordo com a advogada especialista em Direito de Fam\u00edlia, Gisele Martorelli, em entrevista ao portal e-Investidor, &#8220;o STF entende a previd\u00eancia como um v\u00ednculo contratual privado, o que impede a cobran\u00e7a do ITCMD&#8221;. Os planos de previd\u00eancia tamb\u00e9m proporcionam benef\u00edcios fiscais, como o adiamento do Imposto de Renda (IR), tornando-os op\u00e7\u00f5es vantajosas para quem busca transferir patrim\u00f4nio com menor carga tribut\u00e1ria.<\/p>\n\n\n\n<p>Ainda n\u00e3o est\u00e1 claro se a decis\u00e3o ser\u00e1 retroativa, mas, se for, os contribuintes poder\u00e3o pedir o reembolso dos valores pagos no passado. De acordo com o consultor jur\u00eddico Luiz Felipe Baggio, tamb\u00e9m ao e-Investidor, os Estados provavelmente aumentar\u00e3o a fiscaliza\u00e7\u00e3o sobre outros bens sujeitos ao ITCMD, com o objetivo de compensar a queda na arrecada\u00e7\u00e3o causada pela mudan\u00e7a.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Heran\u00e7a<\/strong><\/h3>\n\n\n\n<p>A heran\u00e7a consiste no conjunto de bens, direitos e deveres que uma pessoa falecida deixa para seus herdeiros. No Brasil, ela pode ser leg\u00edtima, quando distribu\u00edda conforme as regras do <a href=\"https:\/\/www12.senado.leg.br\/noticias\/especiais\/especial-cidadania\/heranca\/novo-codigo-civil-quem-pode-ser-herdeiro\" target=\"_blank\" rel=\"noopener\">C\u00f3digo Civil<\/a>, ou testament\u00e1ria, quando determinada por testamento. Os principais tipos de heran\u00e7a s\u00e3o a leg\u00edtima, a testament\u00e1ria, a jacente (quando n\u00e3o h\u00e1 herdeiros) e a vacante (quando n\u00e3o h\u00e1 donos, sendo destinada ao poder p\u00fablico).<\/p>\n\n\n\n<p>A partilha da heran\u00e7a acontece ap\u00f3s o invent\u00e1rio, com metade dos bens sendo distribu\u00edda entre os herdeiros necess\u00e1rios e a outra metade conforme a vontade do falecido. Herdeiros podem ser desconsiderados por indignidade ou deserda\u00e7\u00e3o, em situa\u00e7\u00f5es como homic\u00eddios ou ofensas graves contra o falecido.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O conhecido imposto sobre heran\u00e7a sofreu modifica\u00e7\u00f5es pelo STF no ano passado; saiba o que come\u00e7ou a valer a partir desse ano<\/p>\n","protected":false},"author":3,"featured_media":3450,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":{"format":"standard"},"jnews_primary_category":[],"jnews_social_meta":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":""},"categories":[84,83],"tags":[],"class_list":["post-3449","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mais-tendencias","category-colunas"],"_referencia":"","_links":{"self":[{"href":"https:\/\/tribunademinas.com.br\/colunas\/maistendencias\/wp-json\/wp\/v2\/posts\/3449","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tribunademinas.com.br\/colunas\/maistendencias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tribunademinas.com.br\/colunas\/maistendencias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tribunademinas.com.br\/colunas\/maistendencias\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/tribunademinas.com.br\/colunas\/maistendencias\/wp-json\/wp\/v2\/comments?post=3449"}],"version-history":[{"count":1,"href":"https:\/\/tribunademinas.com.br\/colunas\/maistendencias\/wp-json\/wp\/v2\/posts\/3449\/revisions"}],"predecessor-version":[{"id":3451,"href":"https:\/\/tribunademinas.com.br\/colunas\/maistendencias\/wp-json\/wp\/v2\/posts\/3449\/revisions\/3451"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tribunademinas.com.br\/colunas\/maistendencias\/wp-json\/wp\/v2\/media\/3450"}],"wp:attachment":[{"href":"https:\/\/tribunademinas.com.br\/colunas\/maistendencias\/wp-json\/wp\/v2\/media?parent=3449"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tribunademinas.com.br\/colunas\/maistendencias\/wp-json\/wp\/v2\/categories?post=3449"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tribunademinas.com.br\/colunas\/maistendencias\/wp-json\/wp\/v2\/tags?post=3449"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}