{"id":34154,"date":"2025-11-09T16:45:00","date_gmt":"2025-11-09T19:45:00","guid":{"rendered":"https:\/\/tribunademinas.com.br\/colunas\/maistendencias\/?p=34154"},"modified":"2025-11-10T10:49:01","modified_gmt":"2025-11-10T13:49:01","slug":"pendrive-morre-e-surge-nova-tecnologia-para-guardar-dados","status":"publish","type":"post","link":"https:\/\/tribunademinas.com.br\/colunas\/maistendencias\/pendrive-morre-e-surge-nova-tecnologia-para-guardar-dados\/","title":{"rendered":"Pendrive morre e surge nova tecnologia para guardar dados"},"content":{"rendered":"\n<p>Por cerca de duas d\u00e9cadas, as mem\u00f3rias <a href=\"https:\/\/www.infowester.com\/usb.php#:~:text=USB%20(Universal%20Serial%20Bus)%20%C3%A9,para%20cada%20tipo%20de%20equipamento.\" target=\"_blank\" rel=\"noopener\">USB<\/a>, ou pendrives, foram essenciais para transferir documentos, armazenar trabalhos acad\u00eamicos e compartilhar arquivos com agilidade. Hoje, por\u00e9m, v\u00eam sendo substitu\u00eddas por tecnologias mais modernas e seguras, ficando restritas a usos pontuais.<\/p>\n\n\n\n<p>O sucesso dos pendrives se deu em um per\u00edodo em que outras formas de transfer\u00eancia eram limitadas ou caras. Superando as restri\u00e7\u00f5es de disquetes e CDs, ofereceram maior armazenamento, compatibilidade entre sistemas e dispensaram softwares adicionais, tornando-se indispens\u00e1veis para profissionais, estudantes e usu\u00e1rios dom\u00e9sticos.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Fim do pendrive<\/strong><\/h2>\n\n\n<style>@media (min-width: 992px) {\n    .recomendadorV2Area1 {\n        width: 280px;\n    }\n    .recomendadorV2Area2 {\n        padding: 0px 20px;\n        width: calc(100% - 280px);\n    }\n}\n\n@media (max-width: 992px) {\n    .recomendadorV2Button {\n        margin: 0 auto;\n    }\n    .recomendadorV2Area {\n        flex-direction: column;\n        text-align: center;\n    }\n    .recomendadorV2Area2 {\n        padding: 0px 20px;\n    }\n}\n\n.recomendadorV2Area {\n    background: #eeeeee3d;\n    border-radius: 10px;\n    padding: 15px;\n    display: flex;\n    margin: 15px auto;\n    border: 1px solid #00000014;\n    max-width: 800px;\n}\n\n.recomendadorV2Area1 img {\n    width: 280px;\n    height: auto;\n    border-radius: 8px;\n}\n\n.linkrecomendadorv2 {\n    text-decoration: none !important;\n}\n\n.recomendadorV2Area2 .recomendadorV2Type {\n    text-transform: uppercase;\n    font-weight: 500;\n    font-size: 11px;\n    letter-spacing: 2px;\n    color: #666;\n    margin: 12px 0;\n    display: block;\n}\n\n.recomendadorV2Title h2 {\n    padding-top: 0px !important;\n    margin: 0px !important;\n    border-left: none !important;\n    padding-left: 0px !important;\n    line-height: 1.3;\n    color: #000 !important;\n    font-size: 24px;\n    margin-bottom: 12px !important;\n}\n\n.recomendadorV2Desc {\n    color: #333;\n    margin: 12px 0px !important;\n    font-size: 15px;\n    line-height: 1.5;\n}\n\n.recomendadorV2Button {\n    width: auto;\n    max-width: 200px;\n    margin: 0;\n    display: inline-flex;\n    align-items: center;\n    background: #1D3557;\n    border-radius: 8px;\n    color: #fff;\n    height: 36px;\n    justify-content: center;\n    text-align: center;\n    font-size: 14px;\n    padding: 0 20px;\n    transition: background-color 0.2s ease;\n}\n\n.recomendadorV2Button:hover {\n    background: #2a4d7a;\n}\n\n.recomendadorV2Button:after {\n    margin-top: -2px;\n    content: \"\u2192\";\n    padding: 0px 0px 0px 8px;\n}\n\n.recomendadorV2Alert {\n    text-align: left;\n    font-size: 11px;\n    margin-top: 8px;\n    color: #666;\n}\n\n.recomendadorFixedArea {\n    width: 100%;\n    display: flex;\n    justify-content: center;\n    align-items: center;\n}\n\n@media (min-width: 992px) {\n    #recomendadorFixed {\n        width: 32% !important;\n        left: 5%;\n    }\n    .recomendadorCloseFixed{\n        right: inherit !important;\n        left: 378px !important;\n    }\n}\n\n#recomendadorFixed {\n    width: 90%;\n    box-shadow: 0 10px 20px 0px #00000057;\n    display: none;\n    height: 90px;\n    background: #F6F6F6;\n    position: fixed;\n    flex-direction: row;\n    bottom: 10px;\n    z-index: 9999;\n    border-radius: 16px;\n    padding: 7px 10px;\n}\n\n.recomendadorLeftArea {\n    width: 160px;\n}\n\n.recomendadorRightArea h2 {\n    padding-top: 0px;\n    margin: 2px 0px 4px 0px !important;\n    font-weight: 400;\n    text-align: center;\n    padding-left: 0px !important;\n    color: #000 !important;\n    border-left: none !important;\n    line-height: 20px;\n    font-size: 12px !important;\n}\n\n.recomendadorImgFixed {\n    overflow: hidden;\n    padding: 8px 6px;\n    height: 100%;\n}\n\n.recomendadorImgFixed img {\n    height: 100% !important;\n    border-radius: 16px;\n}\n\n.recomendadorRightArea {\n    padding-top: 6px;\n    display: flex;\n    width: calc(100% - 130px);\n    justify-content: space-between;\n    align-items: center;\n    flex-direction: column;\n}\n\n.recomendadorButtonFixed {\n    margin: 0 auto;\n    background: #1D3557;\n    width: 80%;\n    text-align: center;\n    font-size: 10px;\n    color: #FFF;\n    padding: 2px 10px;\n    border-radius: 3px;\n}\n\n.recomendadorButtonFixed:after {\n    margin-top: -3px;\n    content: \"\u2192\";\n    padding: 0px 0px 0px 10px;\n}\n\n.recomendadorAlertFixed {\n    font-weight: 400;\n    text-align: center;\n    color: #484848;\n    font-size: 8px;\n}\n\n.recomendadorCloseFixed {\n    z-index: 99999;\n    display: none;\n    right: 0px;\n    left: inherit;\n    bottom: 99px;\n    position: fixed;\n    justify-content: center;\n    background: #F6F6F6;\n    width: 25px;\n    align-items: center;\n    height: 25px;\n    font-weight: 800;\n    border-radius: 50%;\n    border: 1px solid #EBEBEB;\n}\n\n.recomendadorV2Desc{\n    color: #000000;\n    margin: 20px 0px;\n}\n\n@media (max-width: 576px) {\n    .recomendadorV2Area {\n      padding: 10px;\n      max-width: 100%;\n    }\n  \n    .recomendadorV2Area1 img {\n      width: 100%;\n      border-radius: 6px;\n    }\n  \n    .recomendadorV2Area2 .recomendadorV2Type {\n      font-size: 9px;\n      letter-spacing: 1px;\n      margin: 8px 0;\n    }\n  \n    .recomendadorV2Title h2 {\n      font-size: 18px !important;\n      margin-bottom: 8px !important;\n      line-height: 1.2;\n    }\n  \n    .recomendadorV2Desc {\n      font-size: 14px;\n      margin: 8px 0 !important;\n      line-height: 1.4;\n    }\n  \n    .recomendadorV2Button {\n      font-size: 14px;\n      height: 40px;\n      padding: 0 12px;\n      max-width: 100%;\n      width: 100%;\n    }\n  \n    .recomendadorV2Button:after {\n      padding-left: 6px;\n    }\n  }\n  <\/style>\n        <div class=\"lazyblock-recomendador-v2-2jDGz wp-block-lazyblock-recomendador-v2\">\n        <a class=\"linkrecomendadorv2\" href=\"https:\/\/tribunademinas.com.br\/colunas\/dinheiroecidadania\/6-infracoes-que-vao-suspender-a-cnh-na-mesma-hora-e-ninguem-sabe\/?utm_source=lazy\">\n            <div class=\"recomendadorV2Area\">\n            <div class=\"recomendadorV2Area1\">\n                <div class=\"recomendadorV2Img\">\n                <img class=\"lazyloaded\" decoding=\"async\" src=\"https:\/\/tribunademinas.audiencelabs.com.br\/wp-content\/uploads\/2025\/11\/CNH.jpg\" data-src=\"https:\/\/tribunademinas.audiencelabs.com.br\/wp-content\/uploads\/2025\/11\/CNH.jpg\" alt=\"\">\n                <\/div>\n            <\/div>\n            <div class=\"recomendadorV2Area2\">\n                <div class=\"recomendadorV2Type\">\n                    <span>Risco imediato<\/span>\n                <\/div>\n                <div class=\"recomendadorV2Title\">\n                <h2><span>6 infra\u00e7\u00f5es que suspendem a CNH \ud83d\udea8<\/span><\/h2>\n                <\/div>\n                <div class=\"recomendadorV2Desc\">\n                <span>Voc\u00ea pode perder a habilita\u00e7\u00e3o na hora \u2014 entenda quais s\u00e3o.<\/span>\n                <\/div>\n                <div class=\"recomendadorV2Button\">Saiba mais<\/div>\n                <div class=\"recomendadorV2Alert\"><\/div>\n            <\/div>\n            <\/div>\n        <\/a>\n        <div>\n            <div style=\"z-index:99999;\" id=\"buttonClose\" onclick=\"closeRecomendadorFixed()\">\n            <div class=\"recomendadorCloseFixed\">X<\/div>\n            <\/div>\n            <a href=\"https:\/\/tribunademinas.com.br\/colunas\/dinheiroecidadania\/6-infracoes-que-vao-suspender-a-cnh-na-mesma-hora-e-ninguem-sabe\/?utm_source=lazy\">\n            <div class=\"recomendadorFixedArea\">\n                <div id=\"recomendadorFixed\">\n                <div class=\"recomendadorLeftArea\">\n                    <div class=\"recomendadorImgFixed\">\n                    <img class=\"lazyload\" decoding=\"async\" src=\"https:\/\/tribunademinas.audiencelabs.com.br\/wp-content\/uploads\/2025\/11\/CNH.jpg\" alt=\"\">\n                    <\/div>\n                <\/div>\n                <div class=\"recomendadorRightArea\">\n                    <div class=\"recomendadorTitleFixed\">\n                    <h2><span>6 infra\u00e7\u00f5es que suspendem a CNH \ud83d\udea8<\/span><\/h2>\n                    <\/div>\n                    <div class=\"recomendadorButtonFixed\">Saiba mais<\/div>\n                    <div class=\"recomendadorAlertFixed\"><\/div>\n                <\/div>\n                <\/div>\n            <\/div>\n            <\/a>\n        <\/div>\n        <\/div>\n\n\n\n<p>Com o aumento das exig\u00eancias digitais \u2014 como v\u00eddeos em 4K, arquivos pesados e maior demanda por rapidez \u2014 os pendrives passaram a ser insuficientes. Tr\u00eas fatores principais explicam essa obsolesc\u00eancia:<\/p>\n\n\n\n<ol start=\"1\" class=\"wp-block-list\">\n<li><strong>Armazenamento Limitado<\/strong>: os modelos mais comuns oferecem entre 64 GB e 512 GB, insuficientes para backups completos ou arquivos de alta defini\u00e7\u00e3o. Embora existam unidades de at\u00e9 2 TB, seu custo \u00e9 elevado em compara\u00e7\u00e3o a alternativas como discos SSD externos.<\/li>\n\n\n\n<li><strong>Velocidade Reduzida<\/strong>: a transfer\u00eancia de grandes arquivos em pendrives tradicionais \u00e9 lenta, enquanto SSDs port\u00e1teis com USB-C ou Thunderbolt realizam a mesma opera\u00e7\u00e3o em segundos.<\/li>\n\n\n\n<li><strong>Portas Incompat\u00edveis<\/strong>: o USB-A, padr\u00e3o tradicional desses dispositivos, vem sendo substitu\u00eddo pelo USB-C em notebooks ultrafinos e dispositivos modernos, exigindo adaptadores que nem sempre mant\u00eam velocidade ou confiabilidade.<\/li>\n<\/ol>\n\n\n\n<p>Al\u00e9m das limita\u00e7\u00f5es t\u00e9cnicas, os pendrives tamb\u00e9m apresentam riscos de seguran\u00e7a: s\u00e3o facilmente perdidos ou danificados e podem servir como vetores de malwares, oferecendo amea\u00e7a significativa em ambientes corporativos e institucionais. Mesmo modelos com criptografia ou prote\u00e7\u00e3o por senha n\u00e3o eliminam completamente essas vulnerabilidades.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Novas tecnologias<\/strong><\/h3>\n\n\n\n<p>Como alternativas mais seguras e eficientes, destacam-se os discos SSD externos e os cart\u00f5es SD e microSD, que combinam maior capacidade, durabilidade e compatibilidade com diversos dispositivos. Contudo, a solu\u00e7\u00e3o que mais se consolidou \u00e9 o armazenamento em nuvem.<\/p>\n\n\n\n<p>Plataformas como Google Drive, Dropbox, iCloud e OneDrive permitem acessar e compartilhar arquivos em tempo real, com sincroniza\u00e7\u00e3o autom\u00e1tica, backups cont\u00ednuos e independ\u00eancia de suportes f\u00edsicos, estabelecendo-se como o padr\u00e3o atual para gest\u00e3o de dados pessoais e profissionais.<\/p>\n\n\n\n<style>@media (min-width: 992px) {\n    .recomendadorV2Area1 {\n        width: 280px;\n    }\n    .recomendadorV2Area2 {\n        padding: 0px 20px;\n        width: calc(100% - 280px);\n    }\n}\n\n@media (max-width: 992px) {\n    .recomendadorV2Button {\n        margin: 0 auto;\n    }\n    .recomendadorV2Area {\n        flex-direction: column;\n        text-align: center;\n    }\n    .recomendadorV2Area2 {\n        padding: 0px 20px;\n    }\n}\n\n.recomendadorV2Area {\n    background: #eeeeee3d;\n    border-radius: 10px;\n    padding: 15px;\n    display: flex;\n    margin: 15px auto;\n    border: 1px solid #00000014;\n    max-width: 800px;\n}\n\n.recomendadorV2Area1 img {\n    width: 280px;\n    height: auto;\n    border-radius: 8px;\n}\n\n.linkrecomendadorv2 {\n    text-decoration: none !important;\n}\n\n.recomendadorV2Area2 .recomendadorV2Type {\n    text-transform: uppercase;\n    font-weight: 500;\n    font-size: 11px;\n    letter-spacing: 2px;\n    color: #666;\n    margin: 12px 0;\n    display: block;\n}\n\n.recomendadorV2Title h2 {\n    padding-top: 0px !important;\n    margin: 0px !important;\n    border-left: none !important;\n    padding-left: 0px !important;\n    line-height: 1.3;\n    color: #000 !important;\n    font-size: 24px;\n    margin-bottom: 12px !important;\n}\n\n.recomendadorV2Desc {\n    color: #333;\n    margin: 12px 0px !important;\n    font-size: 15px;\n    line-height: 1.5;\n}\n\n.recomendadorV2Button {\n    width: auto;\n    max-width: 200px;\n    margin: 0;\n    display: inline-flex;\n    align-items: center;\n    background: #1D3557;\n    border-radius: 8px;\n    color: #fff;\n    height: 36px;\n    justify-content: center;\n    text-align: center;\n    font-size: 14px;\n    padding: 0 20px;\n    transition: background-color 0.2s ease;\n}\n\n.recomendadorV2Button:hover {\n    background: #2a4d7a;\n}\n\n.recomendadorV2Button:after {\n    margin-top: -2px;\n    content: \"\u2192\";\n    padding: 0px 0px 0px 8px;\n}\n\n.recomendadorV2Alert {\n    text-align: left;\n    font-size: 11px;\n    margin-top: 8px;\n    color: #666;\n}\n\n.recomendadorFixedArea {\n    width: 100%;\n    display: flex;\n    justify-content: center;\n    align-items: center;\n}\n\n@media (min-width: 992px) {\n    #recomendadorFixed {\n        width: 32% !important;\n        left: 5%;\n    }\n    .recomendadorCloseFixed{\n        right: inherit !important;\n        left: 378px !important;\n    }\n}\n\n#recomendadorFixed {\n    width: 90%;\n    box-shadow: 0 10px 20px 0px #00000057;\n    display: none;\n    height: 90px;\n    background: #F6F6F6;\n    position: fixed;\n    flex-direction: row;\n    bottom: 10px;\n    z-index: 9999;\n    border-radius: 16px;\n    padding: 7px 10px;\n}\n\n.recomendadorLeftArea {\n    width: 160px;\n}\n\n.recomendadorRightArea h2 {\n    padding-top: 0px;\n    margin: 2px 0px 4px 0px !important;\n    font-weight: 400;\n    text-align: center;\n    padding-left: 0px !important;\n    color: #000 !important;\n    border-left: none !important;\n    line-height: 20px;\n    font-size: 12px !important;\n}\n\n.recomendadorImgFixed {\n    overflow: hidden;\n    padding: 8px 6px;\n    height: 100%;\n}\n\n.recomendadorImgFixed img {\n    height: 100% !important;\n    border-radius: 16px;\n}\n\n.recomendadorRightArea {\n    padding-top: 6px;\n    display: flex;\n    width: calc(100% - 130px);\n    justify-content: space-between;\n    align-items: center;\n    flex-direction: column;\n}\n\n.recomendadorButtonFixed {\n    margin: 0 auto;\n    background: #1D3557;\n    width: 80%;\n    text-align: center;\n    font-size: 10px;\n    color: #FFF;\n    padding: 2px 10px;\n    border-radius: 3px;\n}\n\n.recomendadorButtonFixed:after {\n    margin-top: -3px;\n    content: \"\u2192\";\n    padding: 0px 0px 0px 10px;\n}\n\n.recomendadorAlertFixed {\n    font-weight: 400;\n    text-align: center;\n    color: #484848;\n    font-size: 8px;\n}\n\n.recomendadorCloseFixed {\n    z-index: 99999;\n    display: none;\n    right: 0px;\n    left: inherit;\n    bottom: 99px;\n    position: fixed;\n    justify-content: center;\n    background: #F6F6F6;\n    width: 25px;\n    align-items: center;\n    height: 25px;\n    font-weight: 800;\n    border-radius: 50%;\n    border: 1px solid #EBEBEB;\n}\n\n.recomendadorV2Desc{\n    color: #000000;\n    margin: 20px 0px;\n}\n\n@media (max-width: 576px) {\n    .recomendadorV2Area {\n      padding: 10px;\n      max-width: 100%;\n    }\n  \n    .recomendadorV2Area1 img {\n      width: 100%;\n      border-radius: 6px;\n    }\n  \n    .recomendadorV2Area2 .recomendadorV2Type {\n      font-size: 9px;\n      letter-spacing: 1px;\n      margin: 8px 0;\n    }\n  \n    .recomendadorV2Title h2 {\n      font-size: 18px !important;\n      margin-bottom: 8px !important;\n      line-height: 1.2;\n    }\n  \n    .recomendadorV2Desc {\n      font-size: 14px;\n      margin: 8px 0 !important;\n      line-height: 1.4;\n    }\n  \n    .recomendadorV2Button {\n      font-size: 14px;\n      height: 40px;\n      padding: 0 12px;\n      max-width: 100%;\n      width: 100%;\n    }\n  \n    .recomendadorV2Button:after {\n      padding-left: 6px;\n    }\n  }\n  <\/style>\n        <div class=\"lazyblock-recomendador-v2-2jDGz wp-block-lazyblock-recomendador-v2\">\n        <a class=\"linkrecomendadorv2\" href=\"https:\/\/tribunademinas.com.br\/colunas\/maistendencias\/o-que-acontece-se-remover-o-pendrive-sem-seguranca\/\">\n            <div class=\"recomendadorV2Area\">\n            <div class=\"recomendadorV2Area1\">\n                <div class=\"recomendadorV2Img\">\n                <img class=\"lazyloaded\" decoding=\"async\" src=\"https:\/\/tribunademinas.com.br\/colunas\/maistendencias\/wp-content\/uploads\/2025\/05\/000000-37.jpg\" data-src=\"https:\/\/tribunademinas.com.br\/colunas\/maistendencias\/wp-content\/uploads\/2025\/05\/000000-37.jpg\" alt=\"\">\n                <\/div>\n            <\/div>\n            <div class=\"recomendadorV2Area2\">\n                <div class=\"recomendadorV2Type\">\n                    <span> Seguran\u00e7a do PC<\/span>\n                <\/div>\n                <div class=\"recomendadorV2Title\">\n                <h2><span> O que acontece se remover o pendrive sem seguran\u00e7a?<\/span><\/h2>\n                <\/div>\n                <div class=\"recomendadorV2Desc\">\n                <span> A eje\u00e7\u00e3o de pendrive n\u00e3o \u00e9 mais obrigat\u00f3ria, mas ainda \u00e9 recomendada para evitar perdas e ataques cibern\u00e9ticos; saiba os riscos da falta de seguran\u00e7a<\/span>\n                <\/div>\n                <div class=\"recomendadorV2Button\"> saiba mais<\/div>\n                <div class=\"recomendadorV2Alert\"><\/div>\n            <\/div>\n            <\/div>\n        <\/a>\n        <div>\n            <div style=\"z-index:99999;\" id=\"buttonClose\" onclick=\"closeRecomendadorFixed()\">\n            <div class=\"recomendadorCloseFixed\">X<\/div>\n            <\/div>\n            <a href=\"https:\/\/tribunademinas.com.br\/colunas\/maistendencias\/o-que-acontece-se-remover-o-pendrive-sem-seguranca\/\">\n            <div class=\"recomendadorFixedArea\">\n                <div id=\"recomendadorFixed\">\n                <div class=\"recomendadorLeftArea\">\n                    <div class=\"recomendadorImgFixed\">\n                    <img class=\"lazyload\" decoding=\"async\" src=\"https:\/\/tribunademinas.com.br\/colunas\/maistendencias\/wp-content\/uploads\/2025\/05\/000000-37.jpg\" alt=\"\">\n                    <\/div>\n                <\/div>\n                <div class=\"recomendadorRightArea\">\n                    <div class=\"recomendadorTitleFixed\">\n                    <h2><span> O que acontece se remover o pendrive sem seguran\u00e7a?<\/span><\/h2>\n                    <\/div>\n                    <div class=\"recomendadorButtonFixed\"> saiba mais<\/div>\n                    <div class=\"recomendadorAlertFixed\"><\/div>\n                <\/div>\n                <\/div>\n            <\/div>\n            <\/a>\n        <\/div>\n        <\/div>\n","protected":false},"excerpt":{"rendered":"<p>Pendrives perdem relev\u00e2ncia frente a solu\u00e7\u00f5es modernas que oferecem maior capacidade, velocidade e seguran\u00e7a no armazenamento de dados<\/p>\n","protected":false},"author":3,"featured_media":15380,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":{"format":"standard"},"jnews_primary_category":[],"jnews_social_meta":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":""},"categories":[84,83],"tags":[],"class_list":["post-34154","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mais-tendencias","category-colunas"],"_referencia":"","_links":{"self":[{"href":"https:\/\/tribunademinas.com.br\/colunas\/maistendencias\/wp-json\/wp\/v2\/posts\/34154","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tribunademinas.com.br\/colunas\/maistendencias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tribunademinas.com.br\/colunas\/maistendencias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tribunademinas.com.br\/colunas\/maistendencias\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/tribunademinas.com.br\/colunas\/maistendencias\/wp-json\/wp\/v2\/comments?post=34154"}],"version-history":[{"count":2,"href":"https:\/\/tribunademinas.com.br\/colunas\/maistendencias\/wp-json\/wp\/v2\/posts\/34154\/revisions"}],"predecessor-version":[{"id":34410,"href":"https:\/\/tribunademinas.com.br\/colunas\/maistendencias\/wp-json\/wp\/v2\/posts\/34154\/revisions\/34410"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tribunademinas.com.br\/colunas\/maistendencias\/wp-json\/wp\/v2\/media\/15380"}],"wp:attachment":[{"href":"https:\/\/tribunademinas.com.br\/colunas\/maistendencias\/wp-json\/wp\/v2\/media?parent=34154"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tribunademinas.com.br\/colunas\/maistendencias\/wp-json\/wp\/v2\/categories?post=34154"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tribunademinas.com.br\/colunas\/maistendencias\/wp-json\/wp\/v2\/tags?post=34154"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}