{"id":31979,"date":"2025-10-18T09:45:00","date_gmt":"2025-10-18T12:45:00","guid":{"rendered":"https:\/\/tribunademinas.com.br\/colunas\/maistendencias\/?p=31979"},"modified":"2025-10-13T15:03:19","modified_gmt":"2025-10-13T18:03:19","slug":"produtos-para-cabelo-recebem-notificacao-urgente-da-anvisa","status":"publish","type":"post","link":"https:\/\/tribunademinas.com.br\/colunas\/maistendencias\/produtos-para-cabelo-recebem-notificacao-urgente-da-anvisa\/","title":{"rendered":"Produtos para cabelo recebem notifica\u00e7\u00e3o urgente da Anvisa"},"content":{"rendered":"\n<p>Em mais uma a\u00e7\u00e3o voltada \u00e0 prote\u00e7\u00e3o da sa\u00fade p\u00fablica, a <a href=\"https:\/\/www.gov.br\/anvisa\/pt-br\/assuntos\/noticias-anvisa\/2025\/anvisa-determina-a-apreensao-e-o-recolhimento-de-oito-produtos-para-cabelo-sem-registro\" target=\"_blank\" rel=\"noopener\"><strong>Ag\u00eancia Nacional de Vigil\u00e2ncia Sanit\u00e1ria<\/strong><\/a> (Anvisa) determinou, na \u00faltima quinta-feira, dia 9 de outubro, o recolhimento imediato de diversos cosm\u00e9ticos capilares que estavam sendo comercializados irregularmente no pa\u00eds. <\/p>\n\n\n\n<p>A medida afeta diretamente produtos que foram colocados no mercado sem o devido registro no \u00f3rg\u00e3o regulador, contrariando as normas sanit\u00e1rias brasileiras. <\/p>\n\n\n\n<p>O caso envolve a empresa Anne Ind\u00fastria e Com\u00e9rcio de Produtos Qu\u00edmicos Ltda., que distribu\u00eda os itens de forma ilegal.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Produtos para cabelo recebem notifica\u00e7\u00e3o urgente da Anvisa<\/h2>\n\n\n\n<p>A decis\u00e3o da Anvisa se baseia na aus\u00eancia de registro sanit\u00e1rio dos produtos, condi\u00e7\u00e3o obrigat\u00f3ria para que qualquer cosm\u00e9tico seja vendido no Brasil. <\/p>\n\n\n\n<p>Sem esse controle, n\u00e3o \u00e9 poss\u00edvel garantir que os itens atendem aos padr\u00f5es m\u00ednimos de seguran\u00e7a, efic\u00e1cia e qualidade exigidos pela legisla\u00e7\u00e3o vigente. <\/p>\n\n\n\n<p>Diante disso, a ag\u00eancia determinou a suspens\u00e3o completa das atividades relacionadas a esses cosm\u00e9ticos, desde a fabrica\u00e7\u00e3o at\u00e9 o uso final.<\/p>\n\n\n\n<p>Al\u00e9m da empresa Anne, uma segunda fabricante tamb\u00e9m entrou na mira da fiscaliza\u00e7\u00e3o. A Pack for You Ind\u00fastria e Com\u00e9rcio de Cosm\u00e9ticos Ltda. teve um de seus produtos recolhidos e proibidos de circular pelo mesmo motivo: falta de registro. <\/p>\n\n\n\n<p>O produto em quest\u00e3o, voltado ao realinhamento capilar, estava sendo ofertado no mercado de maneira irregular, o que levou \u00e0 ado\u00e7\u00e3o de medidas corretivas imediatas.<\/p>\n\n\n\n<p>Abaixo, est\u00e3o listados os produtos cuja distribui\u00e7\u00e3o, venda e uso est\u00e3o proibidos por decis\u00e3o da Anvisa:<\/p>\n\n\n\n<figure class=\"wp-block-table is-style-stripes\"><table class=\"has-fixed-layout\"><thead><tr><th>Produto<\/th><th>Fabricante<\/th><\/tr><\/thead><tbody><tr><td>Soul Care B.T.X. Organic Hidrate Lise<\/td><td>Anne Ind. e Com. de Produtos Qu\u00edmicos Ltda.<\/td><\/tr><tr><td>M\u00e1scara de Tratamento Botox Pl\u00e1stica do Fios Organic<\/td><td>Anne Ind. e Com. de Produtos Qu\u00edmicos Ltda.<\/td><\/tr><tr><td>Selagem T\u00e9rmica Pl\u00e1stica dos Fios Organic<\/td><td>Anne Ind. e Com. de Produtos Qu\u00edmicos Ltda.<\/td><\/tr><tr><td>M\u00e1scara de Tratamento Botox Pl\u00e1stica dos Fios Nano Cristaliza\u00e7\u00e3o<\/td><td>Anne Ind. e Com. de Produtos Qu\u00edmicos Ltda.<\/td><\/tr><tr><td>M\u00e1scara de Tratamento B.Tox Pl\u00e1stica dos Fios Redutor de Volume<\/td><td>Anne Ind. e Com. de Produtos Qu\u00edmicos Ltda.<\/td><\/tr><tr><td>M\u00e1scara de Tratamento Botox Pl\u00e1stica dos Fios Nano Plastia Marroquina<\/td><td>Anne Ind. e Com. de Produtos Qu\u00edmicos Ltda.<\/td><\/tr><tr><td>Selagem T\u00e9rmica Pl\u00e1stica dos Fios Arginina e A\u00e7a\u00ed<\/td><td>Anne Ind. e Com. de Produtos Qu\u00edmicos Ltda.<\/td><\/tr><tr><td>Rubitox Org\u00e2nico Tecnologia ATH Creme de Realinhamento da Fibra<\/td><td>Pack for You Ind. e Com. de Cosm\u00e9ticos Ltda.<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Orienta\u00e7\u00f5es da Anvisa para consumidores<\/h3>\n\n\n\n<p>A Anvisa refor\u00e7a que <a href=\"https:\/\/tribunademinas.com.br\/colunas\/maistendencias\/anvisa-bate-o-martelo-e-proibe-produto-muito-consumido-pelos-brasileiros\/\"><strong>seu papel<\/strong><\/a> \u00e9 justamente impedir que produtos potencialmente perigosos ou mal formulados cheguem ao consumidor. <\/p>\n\n\n\n<p>O registro no \u00f3rg\u00e3o garante que os cosm\u00e9ticos passaram por avalia\u00e7\u00e3o t\u00e9cnica, respeitando crit\u00e9rios de qualidade e seguran\u00e7a.<\/p>\n\n\n\n<p>A recomenda\u00e7\u00e3o \u00e9 clara: antes de comprar ou usar qualquer produto cosm\u00e9tico, o consumidor deve verificar se o item possui registro ou notifica\u00e7\u00e3o v\u00e1lida na Anvisa.<\/p>\n\n\n\n<p> Isso pode ser feito por meio do site da ag\u00eancia, utilizando o nome do produto ou o n\u00famero do processo. <\/p>\n\n\n\n<p>Produtos sem essa comprova\u00e7\u00e3o devem ser evitados, pois representam riscos \u00e0 sa\u00fade, como rea\u00e7\u00f5es al\u00e9rgicas, queimaduras ou efeitos adversos graves.<\/p>\n\n\n\n<p>Com essa a\u00e7\u00e3o, a Anvisa refor\u00e7a seu compromisso com a sa\u00fade da popula\u00e7\u00e3o e a necessidade de vigil\u00e2ncia constante sobre o setor de cosm\u00e9ticos no Brasil.<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Em mais uma a\u00e7\u00e3o voltada \u00e0 prote\u00e7\u00e3o da sa\u00fade p\u00fablica, a Ag\u00eancia Nacional de Vigil\u00e2ncia Sanit\u00e1ria (Anvisa) determinou, na \u00faltima quinta-feira, dia 9 de outubro, o recolhimento imediato de diversos cosm\u00e9ticos capilares que estavam sendo comercializados irregularmente no pa\u00eds. A medida afeta diretamente produtos que foram colocados no mercado sem o devido registro no \u00f3rg\u00e3o [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":31980,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":{"format":"standard"},"jnews_primary_category":[],"jnews_social_meta":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":""},"categories":[84,83],"tags":[],"class_list":["post-31979","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mais-tendencias","category-colunas"],"_referencia":"","_links":{"self":[{"href":"https:\/\/tribunademinas.com.br\/colunas\/maistendencias\/wp-json\/wp\/v2\/posts\/31979","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tribunademinas.com.br\/colunas\/maistendencias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tribunademinas.com.br\/colunas\/maistendencias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tribunademinas.com.br\/colunas\/maistendencias\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/tribunademinas.com.br\/colunas\/maistendencias\/wp-json\/wp\/v2\/comments?post=31979"}],"version-history":[{"count":1,"href":"https:\/\/tribunademinas.com.br\/colunas\/maistendencias\/wp-json\/wp\/v2\/posts\/31979\/revisions"}],"predecessor-version":[{"id":31981,"href":"https:\/\/tribunademinas.com.br\/colunas\/maistendencias\/wp-json\/wp\/v2\/posts\/31979\/revisions\/31981"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tribunademinas.com.br\/colunas\/maistendencias\/wp-json\/wp\/v2\/media\/31980"}],"wp:attachment":[{"href":"https:\/\/tribunademinas.com.br\/colunas\/maistendencias\/wp-json\/wp\/v2\/media?parent=31979"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tribunademinas.com.br\/colunas\/maistendencias\/wp-json\/wp\/v2\/categories?post=31979"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tribunademinas.com.br\/colunas\/maistendencias\/wp-json\/wp\/v2\/tags?post=31979"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}