{"id":23903,"date":"2025-07-15T07:30:00","date_gmt":"2025-07-15T10:30:00","guid":{"rendered":"https:\/\/tribunademinas.com.br\/colunas\/maistendencias\/?p=23903"},"modified":"2025-07-14T09:01:40","modified_gmt":"2025-07-14T12:01:40","slug":"o-que-aconteceu-com-a-varig-e-de-ficar-com-o-queixo-caido","status":"publish","type":"post","link":"https:\/\/tribunademinas.com.br\/colunas\/maistendencias\/o-que-aconteceu-com-a-varig-e-de-ficar-com-o-queixo-caido\/","title":{"rendered":"O que aconteceu com a Varig \u00e9 de ficar com o queixo ca\u00eddo"},"content":{"rendered":"\n<p>Ao se pensar nos grandes nomes do setor a\u00e9reo, \u00e9 imposs\u00edvel n\u00e3o se lembrar da <strong>Via\u00e7\u00e3o A\u00e9rea Rio-Grandense<\/strong> (ou simplesmente, <strong>Varig<\/strong>), a companhia uma companhia a\u00e9rea brasileira fundada em 1927, em Porto Alegre, no Rio Grande do Sul, pelo alem\u00e3o Otto Ernst Meyer.<\/p>\n\n\n\n<p>Afinal, al\u00e9m de ter se tornado um verdadeiro orgulho nacional ao se consolidar como o maior destaque do setor na Am\u00e9rica Latina, a empresa ainda foi respons\u00e1vel por feitos hist\u00f3ricos, como ser a transportadora oficial da sele\u00e7\u00e3o brasileira de futebol entre as copas de 1966 e 2006.<\/p>\n\n\n\n<p>Mas apesar de seu sucesso, a Varig come\u00e7ou a enfrentar terr\u00edveis crises ap\u00f3s os anos 2000 que resultaram em demiss\u00f5es em massa e decreta\u00e7\u00e3o de fal\u00eancia, deixando assim uma terr\u00edvel mancha na hist\u00f3ria da companhia.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">O auge da Varig<\/h2>\n\n\n\n<p>A Varig come\u00e7ou a ascender no mercado por volta da d\u00e9cada de 1940, quando era presidida pelo empres\u00e1rio Ruben Berta. Na \u00e9poca, a empresa come\u00e7ou a expandir suas opera\u00e7\u00f5es, e iniciou seus primeiros voos internacionais.<\/p>\n\n\n\n<p>No in\u00edcio da d\u00e9cada de 1960, a companhia adquiriu avi\u00f5es mais modernos e outras empresas, passando a dominar as viagens ao exterior. J\u00e1 em meados de 1970, ela se tornou extremamente popular n\u00e3o s\u00f3 por seu itiner\u00e1rio, mas tamb\u00e9m pela qualidade de seu servi\u00e7o de bordo, que chegou a ser comparado ao de algumas das maiores companhias a\u00e9reas do per\u00edodo.<\/p>\n\n\n\n<p>Contando com uma extensa frota, funcion\u00e1rios excepcionais e diversos outros benef\u00edcios para os passageiros, a Varig estava oficialmente consolidada como uma das empresas mais importantes do mercado.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">In\u00edcio da crise e o fim da Varig<\/h2>\n\n\n\n<p>Em 1990, durante o governo Fernando Collor de Mello, a Varig come\u00e7ou a sofrer os primeiros impactos, pois com a abertura do mercado nacional, outras companhias se tornaram fortes concorrentes.<\/p>\n\n\n\n<p>Mesmo com um aumento da demanda de voos, a empresa ga\u00facha acabou n\u00e3o conseguindo acompanhar as mudan\u00e7as por conta de suas pr\u00e1ticas antigas e nada competitivas. Com isso, a Varig acabou perdendo sua relev\u00e2ncia.<\/p>\n\n\n\n<p>Por volta de 2003, a companhia j\u00e1 n\u00e3o conseguia nem mesmo pagar o arrendamento de seus avi\u00f5es. E com o aumento desenfreado de gastos, a Varig acabou sendo obrigada a pedir recupera\u00e7\u00e3o judicial em meados de 2003.<\/p>\n\n\n\n<p>Mesmo com todos os esfor\u00e7os para tentar voltar ao mercado, uma parte da empresa acabou sendo comprada pela Gol em 2007. J\u00e1 a outra parte, que tentou seguir funcionando por meio da Flex Linhas A\u00e9reas, fechou as portas rapidamente.<\/p>\n\n\n\n<p>Em 20 de agosto de 2010, a fal\u00eancia da Varig foi oficialmente decretada, marcando o fim da trajet\u00f3ria de uma das maiores companhias a\u00e9reas do pa\u00eds e deixando milhares de funcion\u00e1rios desamparados, muitos ainda sem receber os direitos trabalhistas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ao se pensar nos grandes nomes do setor a\u00e9reo, \u00e9 imposs\u00edvel n\u00e3o se lembrar da Via\u00e7\u00e3o A\u00e9rea Rio-Grandense (ou simplesmente, Varig), a companhia uma companhia a\u00e9rea brasileira fundada em 1927, em Porto Alegre, no Rio Grande do Sul, pelo alem\u00e3o Otto Ernst Meyer. Afinal, al\u00e9m de ter se tornado um verdadeiro orgulho nacional ao se [&hellip;]<\/p>\n","protected":false},"author":14,"featured_media":23904,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":{"format":"standard"},"jnews_primary_category":[],"jnews_social_meta":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":""},"categories":[1],"tags":[],"class_list":["post-23903","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geral"],"_referencia":"","_links":{"self":[{"href":"https:\/\/tribunademinas.com.br\/colunas\/maistendencias\/wp-json\/wp\/v2\/posts\/23903","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tribunademinas.com.br\/colunas\/maistendencias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tribunademinas.com.br\/colunas\/maistendencias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tribunademinas.com.br\/colunas\/maistendencias\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/tribunademinas.com.br\/colunas\/maistendencias\/wp-json\/wp\/v2\/comments?post=23903"}],"version-history":[{"count":1,"href":"https:\/\/tribunademinas.com.br\/colunas\/maistendencias\/wp-json\/wp\/v2\/posts\/23903\/revisions"}],"predecessor-version":[{"id":23905,"href":"https:\/\/tribunademinas.com.br\/colunas\/maistendencias\/wp-json\/wp\/v2\/posts\/23903\/revisions\/23905"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tribunademinas.com.br\/colunas\/maistendencias\/wp-json\/wp\/v2\/media\/23904"}],"wp:attachment":[{"href":"https:\/\/tribunademinas.com.br\/colunas\/maistendencias\/wp-json\/wp\/v2\/media?parent=23903"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tribunademinas.com.br\/colunas\/maistendencias\/wp-json\/wp\/v2\/categories?post=23903"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tribunademinas.com.br\/colunas\/maistendencias\/wp-json\/wp\/v2\/tags?post=23903"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}