{"id":22378,"date":"2025-07-01T08:30:00","date_gmt":"2025-07-01T11:30:00","guid":{"rendered":"https:\/\/tribunademinas.com.br\/colunas\/maistendencias\/?p=22378"},"modified":"2025-06-30T20:56:38","modified_gmt":"2025-06-30T23:56:38","slug":"gigante-barragem-chinesa-desacelera-a-terra-confirma-nasa","status":"publish","type":"post","link":"https:\/\/tribunademinas.com.br\/colunas\/maistendencias\/gigante-barragem-chinesa-desacelera-a-terra-confirma-nasa\/","title":{"rendered":"Gigante barragem chinesa desacelera a Terra, confirma Nasa"},"content":{"rendered":"\n<p>A impressionante <strong>barragem das Tr\u00eas Gargantas<\/strong>, na <strong><a href=\"https:\/\/tribunademinas.com.br\/colunas\/maistendencias\/?s=china+\" data-type=\"link\" data-id=\"https:\/\/tribunademinas.com.br\/colunas\/maistendencias\/?s=china+\">China<\/a><\/strong>, considerada a maior usina hidrel\u00e9trica do planeta, tem um efeito mais profundo do que apenas gerar energia: ela est\u00e1 influenciando a <strong>rota\u00e7\u00e3o da Terra<\/strong>. <\/p>\n\n\n\n<p>O fen\u00f4meno, embora sutil, foi confirmado pela <strong><a href=\"https:\/\/www.nasa.gov\/\" data-type=\"link\" data-id=\"https:\/\/www.nasa.gov\/\" target=\"_blank\" rel=\"noopener\">NASA<\/a><\/strong>, que observou uma modifica\u00e7\u00e3o no eixo e na dura\u00e7\u00e3o do dia terrestre associada \u00e0 redistribui\u00e7\u00e3o de massa provocada pelo gigantesco reservat\u00f3rio.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"jeg_video_container jeg_video_content\"><iframe loading=\"lazy\" title=\"\u00e9 verdade que essa USINA altera a ROTA\u00c7\u00c3O da TERRA?\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/yT_eqfUWyS8?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<\/div><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Megaestrutura hidr\u00e1ulica da barragem gera consequ\u00eancias al\u00e9m da engenharia<\/h2>\n\n\n\n<p>Localizada na prov\u00edncia de <strong>Hubei<\/strong>, sobre o rio <strong>Yangtz\u00e9<\/strong>, o terceiro maior curso d\u2019\u00e1gua do mundo, a estrutura tem dimens\u00f5es colossais: s\u00e3o <strong>2.335 metros de comprimento<\/strong> por <strong>185 metros de altura<\/strong>. <\/p>\n\n\n\n<p>Desde sua conclus\u00e3o em 2012, a barragem armazena um volume de aproximadamente <strong>40 km\u00b3 de \u00e1gua<\/strong> \u2014 o equivalente a 10 trilh\u00f5es de gal\u00f5es.<\/p>\n\n\n\n<p>De acordo com o f\u00edsico planet\u00e1rio <strong>Dr. Fong Chao<\/strong>, do <strong>Centro de Voos Espaciais Goddard<\/strong> da NASA, essa enorme massa l\u00edquida, ao ser concentrada em um ponto espec\u00edfico do globo, provoca uma <strong>altera\u00e7\u00e3o no momento de in\u00e9rcia da Terra<\/strong>, ou seja, uma redistribui\u00e7\u00e3o do peso do planeta que impacta diretamente sua rota\u00e7\u00e3o.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Um dia ligeiramente mais longo e o eixo ligeiramente deslocado<\/h2>\n\n\n\n<p>Os cientistas explicam que a \u00e1gua acumulada a <strong>175 metros acima do n\u00edvel do mar<\/strong> exerce um peso significativo. <\/p>\n\n\n\n<p>Essa press\u00e3o sobre a crosta terrestre, ao alterar a distribui\u00e7\u00e3o de massa, <strong>aumenta o momento de in\u00e9rcia do planeta<\/strong>, fazendo com que os dias fiquem <strong>0,06 microssegundos mais longos<\/strong> e que o eixo da Terra sofra um <strong>deslocamento de cerca de 2 cent\u00edmetros<\/strong>.<\/p>\n\n\n\n<p>Embora pare\u00e7am n\u00fameros \u00ednfimos, eles demonstram o qu\u00e3o interligadas est\u00e3o as <strong>a\u00e7\u00f5es humanas em larga escala<\/strong> e os <strong>equil\u00edbrios naturais<\/strong> do planeta. <em>\u201cCada vez que h\u00e1 uma mudan\u00e7a significativa na massa terrestre, h\u00e1 tamb\u00e9m uma mudan\u00e7a na rota\u00e7\u00e3o\u201d<\/em>, destaca o Dr. Chao.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Consequ\u00eancias globais exigem novos olhares sobre megaprojetos<\/h2>\n\n\n\n<p>Esse estudo reacende o debate sobre os <strong>limites do impacto humano no planeta<\/strong>. Mais do que quest\u00f5es ambientais locais ou regionais, obras de tamanha magnitude podem afetar o <strong>comportamento f\u00edsico do pr\u00f3prio planeta<\/strong>. <\/p>\n\n\n\n<p>Embora os efeitos da barragem das Tr\u00eas Gargantas n\u00e3o representem risco direto, eles simbolizam uma tend\u00eancia crescente de altera\u00e7\u00f5es humanas em <strong>escala planet\u00e1ria<\/strong>.<\/p>\n\n\n\n<p>Especialistas em clima, geof\u00edsica e infraestrutura defendem que avalia\u00e7\u00f5es futuras de projetos desse porte considerem n\u00e3o apenas impactos ambientais imediatos, mas tamb\u00e9m poss\u00edveis implica\u00e7\u00f5es <strong>geodin\u00e2micas<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Barragem das Tr\u00eas Gargantas altera levemente a rota\u00e7\u00e3o da Terra, revela estudo da NASA; impacto j\u00e1 alcan\u00e7a a din\u00e2mica planet\u00e1ria<\/p>\n","protected":false},"author":13,"featured_media":22380,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":{"format":"standard"},"jnews_primary_category":[],"jnews_social_meta":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":""},"categories":[1],"tags":[],"class_list":["post-22378","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geral"],"_referencia":"","_links":{"self":[{"href":"https:\/\/tribunademinas.com.br\/colunas\/maistendencias\/wp-json\/wp\/v2\/posts\/22378","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tribunademinas.com.br\/colunas\/maistendencias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tribunademinas.com.br\/colunas\/maistendencias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tribunademinas.com.br\/colunas\/maistendencias\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/tribunademinas.com.br\/colunas\/maistendencias\/wp-json\/wp\/v2\/comments?post=22378"}],"version-history":[{"count":1,"href":"https:\/\/tribunademinas.com.br\/colunas\/maistendencias\/wp-json\/wp\/v2\/posts\/22378\/revisions"}],"predecessor-version":[{"id":22381,"href":"https:\/\/tribunademinas.com.br\/colunas\/maistendencias\/wp-json\/wp\/v2\/posts\/22378\/revisions\/22381"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tribunademinas.com.br\/colunas\/maistendencias\/wp-json\/wp\/v2\/media\/22380"}],"wp:attachment":[{"href":"https:\/\/tribunademinas.com.br\/colunas\/maistendencias\/wp-json\/wp\/v2\/media?parent=22378"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tribunademinas.com.br\/colunas\/maistendencias\/wp-json\/wp\/v2\/categories?post=22378"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tribunademinas.com.br\/colunas\/maistendencias\/wp-json\/wp\/v2\/tags?post=22378"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}